{"id":13672,"date":"2026-03-23T17:58:46","date_gmt":"2026-03-23T17:58:46","guid":{"rendered":"https:\/\/www.fundacionelpilar.cl\/web\/?p=13672"},"modified":"2026-03-23T18:04:01","modified_gmt":"2026-03-23T18:04:01","slug":"comunidad-del-colegio-el-pilar-reflexiono-sobre-la-diversidad-y-el-cuidado-del-agua","status":"publish","type":"post","link":"https:\/\/www.fundacionelpilar.cl\/web\/comunidad-del-colegio-el-pilar-reflexiono-sobre-la-diversidad-y-el-cuidado-del-agua\/","title":{"rendered":"Comunidad del Colegio El Pilar reflexion\u00f3 sobre la diversidad y el cuidado del agua"},"content":{"rendered":"<p><strong>Estudiantes del 8\u00b0 \u00abB\u00bb y el Programa de Integraci\u00f3n Escolar participaron del tradicional acto c\u00edvico de los d\u00edas lunes.<\/strong><!--more--><\/p>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Un llamativo acto c\u00edvico fue el que se vivi\u00f3 esta ma\u00f1ana en el Colegio El Pilar. Los encargados de prepararlo fueron los estudiantes del 8\u00b0 \u00abB\u00bb, junto a su profesor jefe, Luis Schulbach y el Programa de Integraci\u00f3n Escolar, PIE.<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">En una primera parte alumnos presentaron una melod\u00eda tradicional del folclor chilote interpretada en guitarra, acorde\u00f3n y bombo, que estuvo animada tambi\u00e9n por el baile de sus compa\u00f1eras.<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Asimismo, se hizo especial hincapi\u00e9 en la efem\u00e9rides que se celebr\u00f3 ayer domingo en todo el mundo: el D\u00eda Mundial del Agua, donde los pilarinos del segundo ciclo hicieron un sentido llamado a abogar por la gesti\u00f3n sostenible de los recursos h\u00eddricos, haciendo eco del llamado a concientizar sobre la importancia del agua dulce y promover su gesti\u00f3n sostenible.<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Por otro lado y en el marco de la conmemoraci\u00f3n a fechas alusivas sobre la diversidad humana y el valor de la inclusi\u00f3n, nuestra comunidad educativa del Colegio El Pilar, a trav\u00e9s de su Programa de Integraci\u00f3n Escolar, PIE, quiso relevar la importancia de reconocer que todas las personas presentan distintas caracter\u00edsticas, ritmos de aprendizaje, fortalezas y desaf\u00edos, los cuales forman parte de la riqueza y variedad propia de la condici\u00f3n humana.<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">As\u00ed se present\u00f3 la intervenci\u00f3n titulada \u00abLa olla de Ana\u00bb cuyo relato invitaba a trav\u00e9s de una met\u00e1fora sencilla y significativa, a reflexionar sobre las dificultades que muchos de nosotros podemos enfrentar en nuestra vida cotidiana y la importancia del apoyo, la comprensi\u00f3n y la inclusi\u00f3n por parte de la comunidad.<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Cabe recordar que todos los lunes se efect\u00faa un acto c\u00edvico en el Colegio El Pilar, marcando el comienzo de cada semana clases y donde se ir\u00e1n presentando cada uno de los cursos y niveles de este 2026.<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">\n<div id='gallery-1' class='gallery galleryid-13672 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9919.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9919-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9919-300x169.jpg 300w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9919-1024x575.jpg 1024w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9919-768x432.jpg 768w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9919-1536x863.jpg 1536w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9919.jpg 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9916.jpg'><img decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9916-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9916-300x169.jpg 300w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9916-1024x575.jpg 1024w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9916-768x432.jpg 768w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9916-1536x863.jpg 1536w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9916.jpg 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9913.jpg'><img decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9913-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9913-300x169.jpg 300w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9913-1024x575.jpg 1024w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9913-768x432.jpg 768w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9913-1536x863.jpg 1536w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9913.jpg 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<\/div>\n<div dir=\"auto\"><a href=\"https:\/\/www.facebook.com\/photo\/?fbid=1397840585479073&amp;set=pcb.1397859875477144&amp;__cft__[0]=AZaTYfEiqSTgRqmd-0l6Tj_XeQRtjP_8fQe7JpbFNCcziflCV-MLaQiD5LtBsMB-3goIfJD8lAJ3TkZIYzTPZ66fsMIcUAKE6wx5EVBwzh0H_QqEwTE6qErk0m0fCSzYoahBwhZtXZztyVJImXC-mXJkuxuyyAglQD0fo6Pxxqy7OaBJt1phvT64PyBckIUZ-IA&amp;__tn__=*b3H-R\">Ver m\u00e1s im\u00e1genes\u00a0<\/a><\/div>\n<blockquote>\n<div dir=\"auto\" style=\"text-align: center;\"><\/div>\n<\/blockquote>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<blockquote>\n<div dir=\"auto\" style=\"text-align: center;\"><strong><em>Fundaci\u00f3n El Pilar de Ancud: 72 a\u00f1os formando personas \u00edntegras, comprometidas con el desarrollo de la sociedad, el cuidado de la Vida y de la madre tierra.<\/em><\/strong><\/div>\n<\/blockquote>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudiantes del 8\u00b0 \u00abB\u00bb y el Programa de Integraci\u00f3n Escolar participaron del tradicional acto c\u00edvico de los d\u00edas lunes.<\/p>\n","protected":false},"author":5,"featured_media":13679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-13672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colegio"],"_links":{"self":[{"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/posts\/13672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/comments?post=13672"}],"version-history":[{"count":1,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/posts\/13672\/revisions"}],"predecessor-version":[{"id":13678,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/posts\/13672\/revisions\/13678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/media\/13679"}],"wp:attachment":[{"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/media?parent=13672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/categories?post=13672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/tags?post=13672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}