{"id":13659,"date":"2026-03-23T15:55:13","date_gmt":"2026-03-23T15:55:13","guid":{"rendered":"https:\/\/www.fundacionelpilar.cl\/web\/?p=13659"},"modified":"2026-03-23T15:55:13","modified_gmt":"2026-03-23T15:55:13","slug":"reinicio-catequesis-de-primera-comunion-en-el-colegio-el-pilar","status":"publish","type":"post","link":"https:\/\/www.fundacionelpilar.cl\/web\/reinicio-catequesis-de-primera-comunion-en-el-colegio-el-pilar\/","title":{"rendered":"Reinici\u00f3 catequesis de Primera Comuni\u00f3n en el Colegio El Pilar"},"content":{"rendered":"<p><strong>Quedan los \u00faltimos encuentros del grupo de ni\u00f1os que recibir\u00e1 el sacramento pr\u00f3ximamente.<\/strong><!--more--><\/p>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">El pasado jueves 19 de marzo se retom\u00f3 la Catequesis de Primera Comuni\u00f3n en el Colegio El Pilar. La acci\u00f3n marca un hito trascendental en los ni\u00f1os, puesto que restan solo unas semanas para que un grupo de 11 peque\u00f1os del segundo ciclo de educaci\u00f3n b\u00e1sica reciban por primera vez a Jes\u00fas consagrado.<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Por esta raz\u00f3n es que como comunidad educativa animamos a\u00f1o a a\u00f1o a nuestros estudiantes y sus familias a vivir y participar de este proceso de preparaci\u00f3n, no solo como un rito, sino que como una verdadera experiencia de comunidad.<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">De ah\u00ed la importancia de asistir a cada encuentro, m\u00e1s cuando quedan ahora tan solo tres. Por eso les recordamos a los pap\u00e1s que <strong>la Catequesis<\/strong> se efect\u00faa los <strong>jueve<\/strong>s de <strong>16:00<\/strong> a <strong>17:00<\/strong> en la <strong>sala de Pastora<\/strong>l, donde las t\u00edas Yessenia Ule y Marta Arismenidi, catequistas del Colegio, esperan a los ni\u00f1os para guiarlos en este camino, que culminar\u00e1 con el recibimiento del sagrado sacramento.<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Como comunidad educativa en Pastoral, fundamentada en la Espiritualidad de la Encarnaci\u00f3n, nos enorgullece acompa\u00f1ar a estos peque\u00f1os pilarinos en su proceso de fe, pilar fundamental de nuestro proyecto educativo institucional, que anhela y declara ser formadora de personas \u00edntegras, respetuosas, solidarias e inclusivas, perseverantes en la b\u00fasqueda de la excelencia, la verdad y la justicia, con capacidad para contribuir al desarrollo arm\u00f3nico de la sociedad y la naturaleza.<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-13661 \" src=\"https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9861-1024x575.jpg\" alt=\"\" width=\"600\" height=\"337\" srcset=\"https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9861-1024x575.jpg 1024w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9861-300x169.jpg 300w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9861-768x432.jpg 768w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9861-1536x863.jpg 1536w, https:\/\/www.fundacionelpilar.cl\/web\/wp-content\/uploads\/2026\/03\/DSC_9861.jpg 2000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<blockquote>\n<div dir=\"auto\" style=\"text-align: center;\"><em><strong>Fundaci\u00f3n El Pilar de Ancud: 72 a\u00f1os formando personas \u00edntegras, comprometidas con el desarrollo de la sociedad, el cuidado de la Vida y de la madre tierra.<\/strong><\/em><\/div>\n<\/blockquote>\n<div dir=\"auto\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Quedan los \u00faltimos encuentros del grupo de ni\u00f1os que recibir\u00e1 el sacramento pr\u00f3ximamente.<\/p>\n","protected":false},"author":5,"featured_media":13660,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-13659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colegio"],"_links":{"self":[{"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/posts\/13659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/comments?post=13659"}],"version-history":[{"count":1,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/posts\/13659\/revisions"}],"predecessor-version":[{"id":13662,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/posts\/13659\/revisions\/13662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/media\/13660"}],"wp:attachment":[{"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/media?parent=13659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/categories?post=13659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fundacionelpilar.cl\/web\/wp-json\/wp\/v2\/tags?post=13659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}